{"id":1308,"count":2,"description":"","link":"https:\/\/accessallartists.de\/en\/eventer-tag\/og-locke\/","name":"OG LOCKE","slug":"og-locke","taxonomy":"eventer-tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OG LOCKE Archives - Access all artists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accessallartists.de\/en\/Eventer-Schlagwort\/og-locke\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OG LOCKE Archives - Access all artists\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accessallartists.de\/en\/Eventer-Schlagwort\/og-locke\/\" \/>\n<meta property=\"og:site_name\" content=\"Access all artists\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accessallartists.de\/wp-content\/uploads\/2023\/03\/aaa-seo-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@accesallartists\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/accessallartists.de\\\/Eventer-Schlagwort\\\/og-locke\\\/\",\"url\":\"https:\\\/\\\/accessallartists.de\\\/Eventer-Schlagwort\\\/og-locke\\\/\",\"name\":\"OG LOCKE Archives - Access all artists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accessallartists.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accessallartists.de\\\/Eventer-Schlagwort\\\/og-locke\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accessallartists.de\\\/Eventer-Schlagwort\\\/og-locke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/accessallartists.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OG LOCKE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accessallartists.de\\\/#website\",\"url\":\"https:\\\/\\\/accessallartists.de\\\/\",\"name\":\"Access all artists\",\"description\":\"Home of Artists &amp; Concerts\",\"publisher\":{\"@id\":\"https:\\\/\\\/accessallartists.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accessallartists.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accessallartists.de\\\/#organization\",\"name\":\"Access all artists\",\"url\":\"https:\\\/\\\/accessallartists.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accessallartists.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accessallartists.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/aaa-seo-icon-image.jpg\",\"contentUrl\":\"https:\\\/\\\/accessallartists.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/aaa-seo-icon-image.jpg\",\"width\":600,\"height\":600,\"caption\":\"Access all artists\"},\"image\":{\"@id\":\"https:\\\/\\\/accessallartists.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aaa_accessallartists\",\"https:\\\/\\\/x.com\\\/accesallartists\",\"https:\\\/\\\/www.instagram.com\\\/aaa_accessallartists\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWQJiDSzXSCWrjcGmxQwpag\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OG LOCKE Archives - Access all artists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accessallartists.de\/en\/Eventer-Schlagwort\/og-locke\/","og_locale":"en_US","og_type":"article","og_title":"OG LOCKE Archives - Access all artists","og_url":"https:\/\/accessallartists.de\/en\/Eventer-Schlagwort\/og-locke\/","og_site_name":"Access all artists","og_image":[{"width":1200,"height":675,"url":"https:\/\/accessallartists.de\/wp-content\/uploads\/2023\/03\/aaa-seo-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@accesallartists","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/accessallartists.de\/Eventer-Schlagwort\/og-locke\/","url":"https:\/\/accessallartists.de\/Eventer-Schlagwort\/og-locke\/","name":"OG LOCKE Archives - Access all artists","isPartOf":{"@id":"https:\/\/accessallartists.de\/#website"},"breadcrumb":{"@id":"https:\/\/accessallartists.de\/Eventer-Schlagwort\/og-locke\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/accessallartists.de\/Eventer-Schlagwort\/og-locke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/accessallartists.de\/"},{"@type":"ListItem","position":2,"name":"OG LOCKE"}]},{"@type":"WebSite","@id":"https:\/\/accessallartists.de\/#website","url":"https:\/\/accessallartists.de\/","name":"Access all artists","description":"Home of Artists &amp; Concerts","publisher":{"@id":"https:\/\/accessallartists.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accessallartists.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accessallartists.de\/#organization","name":"Access all artists","url":"https:\/\/accessallartists.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accessallartists.de\/#\/schema\/logo\/image\/","url":"https:\/\/accessallartists.de\/wp-content\/uploads\/2023\/03\/aaa-seo-icon-image.jpg","contentUrl":"https:\/\/accessallartists.de\/wp-content\/uploads\/2023\/03\/aaa-seo-icon-image.jpg","width":600,"height":600,"caption":"Access all artists"},"image":{"@id":"https:\/\/accessallartists.de\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aaa_accessallartists","https:\/\/x.com\/accesallartists","https:\/\/www.instagram.com\/aaa_accessallartists","https:\/\/www.youtube.com\/channel\/UCWQJiDSzXSCWrjcGmxQwpag"]}]}},"_links":{"self":[{"href":"https:\/\/accessallartists.de\/en\/wp-json\/wp\/v2\/eventer-tag\/1308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accessallartists.de\/en\/wp-json\/wp\/v2\/eventer-tag"}],"about":[{"href":"https:\/\/accessallartists.de\/en\/wp-json\/wp\/v2\/taxonomies\/eventer-tag"}],"wp:post_type":[{"href":"https:\/\/accessallartists.de\/en\/wp-json\/wp\/v2\/eventer?eventer-tag=1308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}